{"id":2898,"date":"2023-06-01T22:12:35","date_gmt":"2023-06-01T20:12:35","guid":{"rendered":"https:\/\/www.firstcisl.it\/sardegna\/?p=2898"},"modified":"2023-06-01T22:20:28","modified_gmt":"2023-06-01T20:20:28","slug":"assemblea-per-la-piattaforma-per-il-ccnl-abi-a-oristano","status":"publish","type":"post","link":"https:\/\/www.firstcisl.it\/sardegna\/2023\/06\/assemblea-per-la-piattaforma-per-il-ccnl-abi-a-oristano\/","title":{"rendered":"Assemblea per la piattaforma per il CCNL Abi a Oristano"},"content":{"rendered":"<p>Una sala gremita di persone \u00e8 ci\u00f2 che ha atteso noi e le altre organizzazioni sindacali, oggi 1 giugno 2023, per la presentazione della piattaforma per il rinnovo del CCNL Abi a Oristano presso l&#8217;Hostel Rodia.<br \/>\nBen 100 persone, in rappresentanza di tutti gli istituti di credito del territorio, si sono presentate all&#8217;appuntamento con le segreterie regionali e territoriali delle organizzazioni sindacali del settore credito.<br \/>\nSi tratta di una piattaforma assai ambiziosa e articolata di cui i colleghi parlano da lunghi giorni ormai e sono molte le curiosit\u00e0 che attendono risposta.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/PHOTO-2023-06-01-15-12-39.jpg\" alt=\"Il tavolo dei relatori\" \/><\/p>\n<p>Seguendo la formula ormai consolidata in Sardegna di suddividere la piattaforma in 5 diverse parti, i relatori si sono alternati nella presentazione che \u00e8 sempre piuttosto lunga e articolata.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/PHOTO-2023-06-01-15-12-41.jpg\" alt=\"Uno scorcio della sala\" \/><\/p>\n<p>Sergio Mura, Segretario Regionale della First Cisl, si \u00e8 incaricato di spiegare in maniera esauriente il contesto in cui la piattaforma stessa \u00e8 maturata. In particolare modo \u00e8 stata evidenziata l&#8217;esigenza di considerare la reale difficolt\u00e0 dei sindacati di vedere rispettata la lettera e la volont\u00e0 delle parti quando firmano un accordo. Questa piattaforma, infatti, prova anche a porre rimedio ai molti guasti causati dal comportamento delle aziende che non hanno voluto rispettare le prescrizioni dei precedenti contratti.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/PHOTO-2023-06-01-15-18-33.jpg\" alt=\"I relatori\" \/><br \/>\n<strong><em>Sergio Mura, First Cisl, al centro<\/strong><\/em><\/p>\n<p>Le altre parti della relazione sono state presentate da Emanuele Cabboi, Segretario Regionale della Fabi, da Tore Daga della Segreteria Regionale di Unisin, da Piero Carta, della Segreteria Regionale della Fisact Cigl, da Mauro Farigu, Segretario Regionale della Uilca Uil.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/PHOTO-2023-06-01-15-12-41-2.jpg\" alt=\"Un altro scorcio della sala\" \/><\/p>\n<p>I presenti hanno ascoltato con grande attenzione le spiegazioni e si sono detti soddisfatti della piattaforma.<br \/>\nAl momento di metterla ai voti, perci\u00f2, non ci si \u00e8 stupiti del voto unanime dei colleghi del territorio di Oristano che sono stati ampiamente ringraziati per la folta presenza in sala.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-2898-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/VIDEO-2023-06-01-15-26-21.mp4?_=1\" \/><a href=\"https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/VIDEO-2023-06-01-15-26-21.mp4\">https:\/\/www.firstcisl.it\/sardegna\/wp-content\/uploads\/sites\/84\/2023\/06\/VIDEO-2023-06-01-15-26-21.mp4<\/a><\/video><\/div><br \/>\n<em><strong>La grande partecipazione all&#8217;assemblea<\/strong><\/em><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"contrattazione,territori\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1685657555\"\r\n\t            data-title=\"Assemblea per la piattaforma per il CCNL Abi a Oristano\" \r\n\t            data-home=\"https:\/\/www.firstcisl.it\/sardegna\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Una sala gremita di persone \u00e8 ci\u00f2 che ha atteso noi e le altre organizzazioni sindacali, oggi 1 giugno 2023, per la presentazione della piattaforma per il rinnovo del CCNL Abi a Oristano presso l&#8217;Hostel Rodia. Ben 100 persone, in rappresentanza di tutti gli istituti di credito del territorio, si sono presentate all&#8217;appuntamento con le [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":2899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,176],"tags":[93,260,268,251],"class_list":["post-2898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contrattazione","category-territori","tag-abi","tag-assemblea-dei-lavoratori","tag-oristano","tag-piattaforma-ccnl"],"_links":{"self":[{"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/posts\/2898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/comments?post=2898"}],"version-history":[{"count":5,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/posts\/2898\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/posts\/2898\/revisions\/2906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/media?parent=2898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/categories?post=2898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.firstcisl.it\/sardegna\/wp-json\/wp\/v2\/tags?post=2898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}