{"id":5232,"date":"2026-09-02T14:00:02","date_gmt":"2026-09-02T12:00:02","guid":{"rendered":"https:\/\/www.firstcisl.it\/bancobpm\/?p=5232"},"modified":"2026-09-02T12:27:43","modified_gmt":"2026-09-02T10:27:43","slug":"pressioni-commerciali-indebite-il-limite-e-stato-superato-ancora-una-volta","status":"publish","type":"post","link":"https:\/\/www.firstcisl.it\/bancobpm\/2026\/09\/02\/pressioni-commerciali-indebite-il-limite-e-stato-superato-ancora-una-volta\/","title":{"rendered":"Pressioni commerciali indebite: il limite \u00e8 stato superato ancora una volta"},"content":{"rendered":"<p>Nel corso di una recente riunione di allineamento commerciale (Live Event) \u00e8 stata illustrata l\u2019iniziativa intitolata \u201cuno per cinque\u201d e sono state presentate alcune slide dal contenuto per noi inaccettabile. In particolare, viene indicato quanto segue:<\/p>\n<p><i>&#8220;Obiettivo: almeno una polizza a settimana per gestore Privati, Personal e Premium nelle cinque settimane dell&#8217;iniziativa, con particolare attenzione al volume dei premi in linea con le aspettative di recupero\u201d<\/i> <b>(uno per cinque): si tratta di un chiaro ed evidente \u201cobbligo di risultato\u201d<\/b>, escluso dal nostro Contratto Collettivo Nazionale di Lavoro.<\/p>\n<p><i>\u201cLe polizze auto non sono conteggiate ai fini dell\u2019iniziativa\u201d<\/i>: questa indicazione, che inevitabilmente spinge i gestori a concentrare l\u2019attenzione commerciale su altri prodotti,<span class=\"Apple-converted-space\">\u00a0 <\/span>mina alla base l&#8217;essenza stessa della consulenza, il cui fine \u00e8 individuare il prodotto ideale per le reali necessit\u00e0 del cliente.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La normativa, del resto, parla chiaro: <b>la Banca,<\/b> in qualit\u00e0 di distributore assicurativo, <b>\u00e8 tenuta ad evitare ogni forma di conflitto tra i propri obiettivi commerciali e il miglior interesse del cliente.<\/b><b><\/b><\/p>\n<p>Come OO.SS Confederali riteniamo doveroso intervenire con fermezza per denunciare l&#8217;ennesima illegittima forzatura commerciale, ricordando a tutte le colleghe e a tutti i colleghi le tutele normative e contrattuali vigenti contenute nel CCNL e nell\u2019Accordo su Politiche Commerciali e Organizzazione del Lavoro:<\/p>\n<ul>\n<li><b>\u201cObbligazione di mezzi\u201d<\/b>: i dipendenti sono tenuti a mettere a disposizione del datore di lavoro le proprie energie lavorative, la propria professionalit\u00e0 e diligenza, ma si tratta di un impegno che non pu\u00f2 tradursi in azioni ad esito certo e garantito e quindi nemmeno, come sopra accennato, in un \u201cobbligo di risultato\u201d;<\/li>\n<li><b>Divieto di previsione di vendita<\/b>: il nostro accordo sulle politiche commerciali e organizzazione del lavoro vieta espressamente la richiesta di dati previsionali di vendita. Sollecitazioni o monitoraggi volti a verificare &#8220;quante polizze venderai questa settimana&#8221; sono illegittimi;<\/li>\n<li><b>Comunicazione dei dati di produzione<\/b>: ricordiamo che non sussiste alcun obbligo da parte delle lavoratrici e dei lavoratori di comunicare dati aziendali di produzione e\/o reportistica al di fuori delle rigide e ufficiali procedure aziendali previste dal controllo di gestione;<\/li>\n<li><b>Rischi di violazione della normativa IVASS<\/b>: spingere sul collocamento sistematico di prodotti assicurativi legandoli a logiche di vendita a budget temporale o di &#8220;recupero&#8221; espone colleghe e colleghi al rischio concreto di violare le norme IVASS (in primis la verifica della reale adeguatezza e rispondenza del prodotto alle esigenze del cliente), tutelando l&#8217;azienda a discapito della professionalit\u00e0 e della responsabilit\u00e0 individuale della lavoratrice e del lavoratore;<\/li>\n<li>Rientra tra le responsabilit\u00e0 aziendali adottare un\u2019organizzazione del lavoro capace di prevenire, anzich\u00e9 acuire, lo stress lavoro-correlato e i relativi rischi psicosociali.<\/li>\n<\/ul>\n<p><b>COSA FARE:<\/b><\/p>\n<p>Invitiamo tutti le colleghe e tutti i colleghi a non cedere a sollecitazioni illegittime e a svolgere la propria attivit\u00e0 con la massima professionalit\u00e0 e nel rispetto delle normative di trasparenza e tutela del consumatore.<\/p>\n<p>Non siete soli: First CISL, Fisac CGIL e Uilca UIL saranno al fianco di lavoratrici e lavoratori per contrastare ogni singola forzatura. Vi chiediamo di segnalare ai vostri rappresentanti sindacali qualsiasi episodio di pressione indebita, monitoraggio continuo o richiesta impropria di dati.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Diffidiamo i soliti \u201cbattitori di tamburo\u201d dal prendere spunto da queste indicazioni partite dall\u2019alto, per mettere in ulteriore difficolt\u00e0 chi, nonostante le note carenze di organico, ogni giorno lavora per portare a casa i risultati eccezionali tanto decantati da questa azienda.<\/p>\n<p>La professionalit\u00e0 e la tutela delle lavoratrici e dei lavoratori non si svendono per un target!<\/p>\n<p>Milano, 02 settembre 2026<\/p>\n<p><b>COORDINAMENTI GRUPPO BANCO BPM<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p><b>FIRST CISL &#8211; FISAC CGIL &#8211; UILCA UIL<\/b><\/p>\n<p><a href=\"https:\/\/www.firstcisl.it\/bancobpm\/wp-content\/uploads\/sites\/13\/2026\/09\/2026-09-02-Pressioni-commerciali-indebite.pdf\">Scarica il comunicato<\/a><\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"in-primo-piano,news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1788357602\"\r\n\t            data-title=\"Pressioni commerciali indebite: il limite \u00e8 stato superato ancora una volta\" \r\n\t            data-home=\"https:\/\/www.firstcisl.it\/bancobpm\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Nel corso di una recente riunione di allineamento commerciale (Live Event) \u00e8 stata illustrata l\u2019iniziativa intitolata \u201cuno per cinque\u201d e sono state presentate alcune slide dal contenuto per noi inaccettabile. In particolare, viene indicato quanto segue: &#8220;Obiettivo: almeno una polizza a settimana per gestore Privati, Personal e Premium nelle cinque settimane dell&#8217;iniziativa, con particolare attenzione [&hellip;]<\/p>\n","protected":false},"author":113,"featured_media":5236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[48,14,45,28,92,87],"class_list":["post-5232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-primo-piano","category-news","tag-banco-bpm","tag-cristina-cavina","tag-first-cisl","tag-first-cisl-gruppo-banco-bpm","tag-politiche-commerciali","tag-pressioni-commerciali"],"_links":{"self":[{"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/posts\/5232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/comments?post=5232"}],"version-history":[{"count":2,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/posts\/5232\/revisions"}],"predecessor-version":[{"id":5235,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/posts\/5232\/revisions\/5235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/media\/5236"}],"wp:attachment":[{"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/media?parent=5232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/categories?post=5232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.firstcisl.it\/bancobpm\/wp-json\/wp\/v2\/tags?post=5232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}