{"id":4417,"date":"2026-05-13T10:38:42","date_gmt":"2026-05-13T08:38:42","guid":{"rendered":"https:\/\/www.firstcisl.it\/assicurazioni\/?p=4417"},"modified":"2026-05-13T13:04:39","modified_gmt":"2026-05-13T11:04:39","slug":"rinnovo-contratto-collettivo-nazionale-di-lavoro-ania-piu-salario-piu-diritti-difeso-il-futuro-dei-giovani","status":"publish","type":"post","link":"https:\/\/www.firstcisl.it\/assicurazioni\/rinnovo-contratto-collettivo-nazionale-di-lavoro-ania-piu-salario-piu-diritti-difeso-il-futuro-dei-giovani\/","title":{"rendered":"Rinnovo Contratto collettivo nazionale di lavoro Ania: pi\u00f9 salario, pi\u00f9 diritti, difeso il futuro dei giovani"},"content":{"rendered":"<p><em>Si riporta il <strong><a href=\"https:\/\/www.firstcisl.it\/assicurazioni\/wp-content\/uploads\/sites\/5\/2026\/05\/Rinnovo_Ccnl_Ania_20260513.pdf\" target=\"_blank\" rel=\"noopener\">comunicato unitario<\/a><\/strong> delle Segreterie nazionali First Cisl, Fisac Cgil, Fna, Snfia e Uilca<\/em><\/p>\n<h4 style=\"text-align: center;\">Contratto collettivo nazionale di lavoro Ania rinnovato: pi\u00f9 salario, pi\u00f9 diritti, difeso il futuro dei giovani<\/h4>\n<p class=\"p1\">Nella notte del 13 maggio \u00e8 stata raggiunta l\u2019ipotesi di rinnovo del Contratto collettivo nazionale di lavoro (Ccnl) Ania, con vigenza 1\u00b0 gennaio 2025 &#8211; 31 maggio 2028, al termine di una trattativa serrata.<\/p>\n<p class=\"p1\">Il risultato raggiunto rappresenta un esito complessivamente positivo e coerente con il mandato assembleare conferito dalle lavoratrici e dai lavoratori. La piattaforma sindacale era stata presentata nel dicembre 2025 con l\u2019intento di rinnovare rapidamente il contratto nazionale, mettere al centro la tutela economica della categoria e difendere e rafforzare l\u2019impianto contrattuale. Riteniamo, in relazione a questi propositi, di aver raggiunto un risultato complessivamente soddisfacente.<\/p>\n<p class=\"p1\">In poco pi\u00f9 di cinque mesi di confronto negoziale \u00e8 stato infatti definito un rinnovo che garantisce un importante avanzamento salariale, consolidando i diritti e le tutele del settore.<\/p>\n<p class=\"p1\">Sul piano economico, l\u2019accordo prevede un incremento retributivo a regime, pari a 280 euro mensili per il quarto livello, settima classe, pari a un incremento dell\u201911,48% e cos\u00ec distribuito:<\/p>\n<ul>\n<li>100 euro dal 1\u00b0 gennaio 2026<\/li>\n<li>100 euro dal 1\u00b0 gennaio 2027<\/li>\n<li>80 euro dal 1\u00b0 gennaio 2028<\/li>\n<\/ul>\n<p class=\"p1\">L\u2019erogazione della prima tranche e degli arretrati avverr\u00e0 nel mese di luglio.<\/p>\n<p class=\"p2\">Una <em>una tantum<\/em> di 1.000 euro, riferita al quarto livello settima classe, come riconoscimento degli arretrati relativi al 2025, articolata tra 550 euro in busta paga, con opzione Fondo pensione 638 euro, pi\u00f9 450 euro in welfare.<\/p>\n<p class=\"p1\">Certamente rilevante \u00e8 aver difeso le classi di anzianit\u00e0. Il sindacato ha infatti respinto la proposta di Ania che prevedeva l\u2019introduzione di un\u2019ulteriore nuova tabella per i neoassunti con solo 8 classi di anzianit\u00e0 e passaggio dopo 7 anni di servizio dalla prima classe alla seconda. Tale proposta avrebbe determinato effetti fortemente penalizzanti soprattutto per le giovani generazioni e destrutturato l\u2019attuale impianto classificatorio del contratto nazionale. Riteniamo di grande importanza aver tutelato l\u2019equit\u00e0 intergenerazionale e, complessivamente, la qualit\u00e0 del lavoro nel settore.<\/p>\n<p class=\"p1\">L\u2019intesa raggiunta conferma, inoltre, la coerenza con le richieste contenute nella piattaforma sindacale sui principali temi.<\/p>\n<p class=\"p1\">Per quanto riguarda la riduzione dell\u2019orario di lavoro si \u00e8 ottenuto il riconoscimento di ulteriori 6 ore di permesso alle 8 ore gi\u00e0 esistenti (articolo 39).<\/p>\n<p class=\"p1\">Sul tema dei diritti civili abbiamo rafforzato gli aspetti di inclusivit\u00e0 e tutela delle disabilit\u00e0, genitorialit\u00e0 (permessi aggiuntivi per i padri), comporto malattia.<\/p>\n<p class=\"p1\">In tema di intelligenza artificiale (IA), \u00e8 stata concordata una dichiarazione congiunta tra le parti e prevista l\u2019istituzione di comitati paritetici aziendali.<\/p>\n<p class=\"p1\">\u00c8 stata introdotta la fattispecie del volontariato di competenza, che andr\u00e0 disciplinata in sede aziendale.<\/p>\n<p class=\"p1\">Impegno dell\u2019Ania a farsi carico di creare le condizioni per un superamento del <em>dumping<\/em> contrattuale dell\u2019appalto assicurativo.<\/p>\n<p class=\"p1\">Tutela situazioni di fragilit\u00e0 e incremento economico per i produttori, aggiuntivo all\u2019importo previsto per tutto il personale, del 7% sul primo livello e del 3% sul secondo livello.<\/p>\n<p class=\"p1\">Per quanto riguarda gli addetti ai Contact center, seguendo una prassi gi\u00e0 in uso nel settore ed in caso di tensioni occupazionali, Ania ha formulato una raccomandazione per la tutela occupazionale e professionale.<\/p>\n<p class=\"p1\">Per quanto riguarda gli inquadramenti professionali, \u00e8 stato definito esclusivamente un limitato ampliamento temporale della fungibilit\u00e0 condizionata tra quarto e quinto livello, che passa da 8 a 12 mesi. Al di fuori di questo intervento circoscritto, le ulteriori richieste avanzate da Ania sono state respinte in quanto destrutturanti dell\u2019attuale impianto degli inquadramenti che prevedeva fungibilit\u00e0 piena, a salire e scendere, tra quarto, quinto, sesto livello.<\/p>\n<p class=\"p1\">Ex Aisa<b>:<\/b> riconoscimento economico con la stessa percentuale di Ania, pari all\u201911,48%, per il 2025, 2026 e 2027, con ultima tranche a gennaio 2028.<br \/>\n<em>Una tantum<\/em> di 450 euro con opzione di 522 euro con versamento in fondo pensione e <em>una tantum<\/em> di 350 euro in conto welfare.<\/p>\n<p class=\"p1\">A partire da giugno saranno convocate le assemblee in tutto il settore per l\u2019illustrazione, discussione e approvazione dell\u2019ipotesi di intesa da parte delle lavoratrici e dei lavoratori.<\/p>\n<p class=\"p1\">Il giudizio delle organizzazioni sindacali sull\u2019ipotesi di intesa raggiunta \u00e8 complessivamente positivo: il rinnovo contrattuale ottenuto rafforza salari, diritti e tutele e difende le giovani generazioni.<\/p>\n<p><em>Milano, 13 maggio 2026<\/em><\/p>\n<p class=\"p4\" style=\"text-align: center;\"><b>Le Segreterie nazionali<\/b><br \/>\n<strong>First Cisl\u00a0 \u00a0&#8211;\u00a0 \u00a0Fisac Cgil\u00a0 \u00a0&#8211;\u00a0 \u00a0Fna\u00a0 \u00a0&#8211;\u00a0 \u00a0Snfia\u00a0 \u00a0&#8211;\u00a0 \u00a0Uilca<\/strong><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p class=\"p5\"><em>Il <strong><a href=\"https:\/\/www.firstcisl.it\/assicurazioni\/wp-content\/uploads\/sites\/5\/2026\/05\/Rinnovo_Ccnl_Ania_20260513.pdf\" target=\"_blank\" rel=\"noopener\">comunicato unitario<\/a><\/strong>\u00a0delle Segreterie nazionali First Cisl, Fisac Cgil, Fna, Snfia e Uilca<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"ania\" \r\n\t            data-modified=\"-27\"\r\n\t            data-created=\"1778668722\"\r\n\t            data-title=\"Rinnovo Contratto collettivo nazionale di lavoro Ania: pi\u00f9 salario, pi\u00f9 diritti, difeso il futuro dei giovani\" \r\n\t            data-home=\"https:\/\/www.firstcisl.it\/assicurazioni\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Si riporta il comunicato unitario delle Segreterie nazionali First Cisl, Fisac Cgil, Fna, Snfia e Uilca Contratto collettivo nazionale di lavoro Ania rinnovato: pi\u00f9 salario, pi\u00f9 diritti, difeso il futuro dei giovani Nella notte del 13 maggio \u00e8 stata raggiunta l\u2019ipotesi di rinnovo del Contratto collettivo nazionale di lavoro (Ccnl) Ania, con vigenza 1\u00b0 gennaio [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":4418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[16,208,22,58,474,95,480,479],"class_list":["post-4417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ania","tag-assicurativi","tag-ccnl-ania","tag-comunicati-stampa","tag-comunicato-unitario","tag-piattaforma-ania","tag-rinnovo-ccnl-ania","tag-tutela-contrattuale","tag-tutela-economica"],"_links":{"self":[{"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/posts\/4417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/comments?post=4417"}],"version-history":[{"count":7,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/posts\/4417\/revisions"}],"predecessor-version":[{"id":4427,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/posts\/4417\/revisions\/4427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/media\/4418"}],"wp:attachment":[{"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/media?parent=4417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/categories?post=4417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.firstcisl.it\/assicurazioni\/wp-json\/wp\/v2\/tags?post=4417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}